{"id":566653,"date":"2024-05-09T01:50:33","date_gmt":"2024-05-09T01:50:33","guid":{"rendered":"https:\/\/world-schools.com\/schools\/sek-international-school-online\/"},"modified":"2025-09-19T14:32:05","modified_gmt":"2025-09-19T14:32:05","slug":"sek-international-school-online","status":"publish","type":"schools","link":"https:\/\/world-schools.com\/it\/schools\/sek-international-school-online\/","title":{"rendered":"SEK International School Global Campus"},"content":{"rendered":"<p>Dal 1892, SEK International Schools \u00e8 all'avanguardia nell'educazione infantile e offre con orgoglio l'International Baccalaureate (IB) dal 1977. Il nostro Diploma Programme (DP) completamente online prosegue la nostra tradizione di innovazione educativa, rendendo l'apprendimento di alta qualit\u00e0 accessibile agli studenti di et\u00e0 compresa tra 16 e 19 anni in tutto il mondo, indipendentemente dalle loro situazioni specifiche. SEK International Schools utilizza il proprio esclusivo Future Learning Model, un metodo di apprendimento il cui obiettivo principale \u00e8 sviluppare l'intelligenza e instillare valori in ciascuno dei suoi studenti.<\/p>\n<p>Il modello di apprendimento futuro SEK:<\/p>\n<p>Promuove un apprendimento flessibile, personalizzato e collaborativo, con metodologie e strumenti adattati all'ambiente virtuale.<\/p>\n<p>Incoraggia il pensiero critico, la risoluzione di problemi concreti e l'imprenditorialit\u00e0 e soddisfa le esigenze attuali e future degli studenti.<\/p>\n<p>Permette agli studenti di partecipare attivamente al proprio processo di apprendimento<\/p>\n<p>Nel programma Diploma online utilizziamo lo stesso approccio di apprendimento basato su indagine, discussione e competenze che caratterizza tutte le scuole SEK.<\/p>\n<p>Gli studenti sviluppano le proprie conoscenze in modo collaborativo sotto la guida dei docenti, oltre a lavorare e interagire con i colleghi.<\/p>\n<p>Abbiamo integrato le linee guida didattiche IB con il profilo di competenza del SEK Education Group, per creare un modello di apprendimento completo che favorisca i risultati accademici e lo sviluppo degli studenti.<\/p>","protected":false},"excerpt":{"rendered":"<p>Since 1892, SEK International Schools has been at the forefront of childhood education, proudly offering the International Baccalaureate (IB) since 1977. Our fully online Diploma Programme (DP) continues our tradition of educational innovation, making high-quality learning accessible to students aged 16-19 worldwide, no matter what their unique situations.SEK International Schools employ their own, exclusive Future [&hellip;]<\/p>\n","protected":false},"author":296,"featured_media":566285,"template":"","meta":{"content-type":"","inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jf_save_progress":"","address":"C. Castillo de Manzanares, 28692 Villafranca del Castillo, Madrid","contact_email":"mariaelizabeth.pesantez@sek.es","website":"https:\/\/www.sek.es\/en\/sek-international-schools\/international-baccalaureate-online\/","min_age":"16","max_age":"19","foundation":"1892","number_of_students":"7000","curricula_description":"<p>International Baccaulaureate<\/p>\n","extra_curricula_description":"","accommodation_description":"","day_school_min_yearly_fee_in_usd":"","cost_description_day_students":"","boarding_school_min_yearly_fee_in_usd":"","cost_description_boarding_students":"","accreditations":"IB, NEASC, CIS and Round Square accreditation","enrollment_phase":"16 - 19 years old","staff_student_ratio":"","health_amp_safety":"","nr_of_nationalities":"80","min_number_of_months_enrollment":"12","facilities_description":"","name_extra_campus_1":"","description_extra_campus_1":"","address_extra_campus_1":"","yearly_fee_min":"13800","yearly_fee_max":"","fee_currency":"eur","scholarship_description":"","online_learning_information":"","online_student_support":"","technology_platform":"","online_community":"","why_choose_reason_1":"Pioneers in Online International Baccalaureate.","why_choose_reason_2":"Tailored learning with Personal Projects.","why_choose_reason_3":"Global community with 70+ nationalities.","chargebee_subscription_id":"2363393000011751359","plan":"1"},"boarding-option":[],"time-zones":[10906,10907,10894,10893,10908],"scholarship":[],"learning-formats":[],"extra-curricular-activities":[],"special-needs":[],"examination":[5315],"religion":[],"language-of-instruction":[10309],"language-lessons":[10327],"curricula":[10325],"gender":[10315],"type-of-school":[10357],"student-age":[10319],"region":[5303,5306,5305],"facilities":[],"class_list":["post-566653","schools","type-schools","status-publish","has-post-thumbnail","hentry","time-zones-utc01","time-zones-utc02","time-zones-utc03","time-zones-utc04","time-zones-utc0530","examination-ib-diploma","language-of-instruction-english","language-lessons-spanish","curricula-ib","gender-co-education","type-of-school-online-school","student-age-13-19-yo","region-europe","region-madrid","region-spain"],"_links":{"self":[{"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/schools\/566653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/schools"}],"about":[{"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/types\/schools"}],"author":[{"embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/users\/296"}],"version-history":[{"count":0,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/schools\/566653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/media\/566285"}],"wp:attachment":[{"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/media?parent=566653"}],"wp:term":[{"taxonomy":"boarding-option","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/boarding-option?post=566653"},{"taxonomy":"time-zones","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/time-zones?post=566653"},{"taxonomy":"scholarship","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/scholarship?post=566653"},{"taxonomy":"learning-formats","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/learning-formats?post=566653"},{"taxonomy":"extra-curricular-activities","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/extra-curricular-activities?post=566653"},{"taxonomy":"special-needs","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/special-needs?post=566653"},{"taxonomy":"examination","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/examination?post=566653"},{"taxonomy":"religion","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/religion?post=566653"},{"taxonomy":"language-of-instruction","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/language-of-instruction?post=566653"},{"taxonomy":"language-lessons","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/language-lessons?post=566653"},{"taxonomy":"curricula","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/curricula?post=566653"},{"taxonomy":"gender","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/gender?post=566653"},{"taxonomy":"type-of-school","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/type-of-school?post=566653"},{"taxonomy":"student-age","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/student-age?post=566653"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/region?post=566653"},{"taxonomy":"facilities","embeddable":true,"href":"https:\/\/world-schools.com\/it\/wp-json\/wp\/v2\/facilities?post=566653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}